{"id":3860,"date":"2024-06-04T09:33:33","date_gmt":"2024-06-04T13:33:33","guid":{"rendered":"https:\/\/3inone.ca\/?page_id=3860"},"modified":"2024-06-04T09:33:33","modified_gmt":"2024-06-04T13:33:33","slug":"demande-de-droits-du-consommateur","status":"publish","type":"page","link":"https:\/\/3inone.ca\/fr\/demande-de-droits-du-consommateur\/","title":{"rendered":"Demande de droits du consommateur"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/multi-column-content.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3860","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Demande de droits du consommateur - 3-IN-ONE Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/3inone.ca\/fr\/demande-de-droits-du-consommateur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demande de droits du consommateur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/3inone.ca\/fr\/demande-de-droits-du-consommateur\/\" \/>\n<meta property=\"og:site_name\" content=\"3-IN-ONE Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Original3INONEOil\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.3inone.ca\/app\/uploads\/2022\/01\/01065733\/3in1-Logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1598\" \/>\n\t<meta property=\"og:image:height\" content=\"1264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/demande-de-droits-du-consommateur\\\/\",\"url\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/demande-de-droits-du-consommateur\\\/\",\"name\":\"Demande de droits du consommateur - 3-IN-ONE Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/#website\"},\"datePublished\":\"2024-06-04T13:33:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/demande-de-droits-du-consommateur\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/3inone.ca\\\/fr\\\/demande-de-droits-du-consommateur\\\/\"]}],\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Comment vaporiser de la silicone sur un tapis de course ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Il est important de lubrifier votre tapis de course pour qu'il fonctionne correctement. Avant de commencer, assurez-vous que votre appareil est d\u00e9branch\u00e9. Consultez le guide du fabricant pour savoir comment desserrer la courroie du tapis roulant afin de pouvoir la soulever et appliquer le lubrifiant. Utilisez le lubrifiant au silicone 3-IN-ONE ou le lubrifiant recommand\u00e9 par le fabricant et vaporisez sous la bande lorsque vous la soulevez. Laissez reposer quelques minutes pour permettre au solvant de s'\u00e9vaporer. R\u00e9p\u00e9tez l'op\u00e9ration des deux c\u00f4t\u00e9s de la machine, en veillant \u00e0 ne pas pulv\u00e9riser de lubrifiant sur le tapis. Si du lubrifiant est pulv\u00e9ris\u00e9 sur le tapis, utilisez de l'eau chaude savonneuse pour le nettoyer compl\u00e8tement. Rebranchez le tapis roulant et faites-le tourner \u00e0 faible vitesse pour permettre au produit de se r\u00e9pandre sur tout le dessous de l'appareil. Une fois le nettoyage termin\u00e9, essuyez les produits d'acc\u00e8s sur les c\u00f4t\u00e9s de l'appareil.\"}},{\"@type\":\"Question\",\"name\":\"How to silicone spray a treadmill?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"It\u2019s important to lubricate your treadmill to keep it running smoothly. Before you start, make sure your device is unplugged. Check the manufacturer\u2019s guide for how to loosen the treadmill belt so that you can lift it and apply the lubricant. Use 3-IN-ONE Silicone Lubricant or the lubricant recommended by the manufacturer and spray underneath the belt as you lift it. Let this sit for a few minutes to allow the solvent to evaporate. Repeat the process on both sides of the machine, taking care not to spray any lubricant on top of the matting. If any lubricant is sprayed onto the matting, use hot, soapy water to clean thoroughly. Plug the treadmill back in and run it at a slow speed to allow the product to spread across the whole underside. Once complete, wipe away any access products from the sides of the machine.\"}},{\"@type\":\"Question\",\"name\":\"Spray au silicone - Quel est son r\u00f4le ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Le lubrifiant au silicone 3-EN-UNE assure une lubrification et une protection anticorrosion de haute performance. Il forme un joint r\u00e9sistant \u00e0 l'eau pour prot\u00e9ger de l'humidit\u00e9 et fournit une couche protectrice au m\u00e9tal, au caoutchouc, au bois et au vinyle. Il r\u00e9duit la friction et l'usure des outils, des pi\u00e8ces et des \u00e9quipements et emp\u00eache la formation de rouille. Il s'agit d'une formulation \u00e0 s\u00e9chage rapide, qui ne tache pas et qui n'attire pas la poussi\u00e8re et la salet\u00e9.\"}},{\"@type\":\"Question\",\"name\":\"Silicone spray \u2013 what does it do?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"3-IN-ONE Silicone Lubricant provides high-performance lubrication and corrosion protection. It provides a water-resistant seal to protect against moisture and provides a protective layer to metal, rubber, wood and vinyl. It reduces friction and wear on tools, parts and equipment and stops rust from forming. It is a quick drying, non-staining formulation that won\u2019t attract dust and dirt.\"}},{\"@type\":\"Question\",\"name\":\"Quand dois-je utiliser une silicone ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Utilisez le lubrifiant au silicone 3-EN-UNE lorsque vous avez besoin d'un lubrifiant haute performance \u00e0 s\u00e9chage rapide qui peut \u00eatre utilis\u00e9 en toute s\u00e9curit\u00e9 sur le m\u00e9tal, le caoutchouc, le bois et le vinyle. Ce lubrifiant laisse un joint r\u00e9sistant \u00e0 l'eau, prot\u00e9geant ainsi de l'humidit\u00e9.\"}},{\"@type\":\"Question\",\"name\":\"When should I use a Silicone?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Use 3-IN-ONE Silicone Lubricant when you need a quick drying, high-performance lubricant that\u2019s safe for use on metal, rubber, wood and vinyl. This lubricant leaves a water-resistant seal, protecting against moisture.\"}},{\"@type\":\"Question\",\"name\":\"O\u00f9 puis-je utiliser le silicone ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Le lubrifiant au silicone 3-EN-UNE peut \u00eatre utilis\u00e9 sur les rails coulissants, les portes et fen\u00eatres en PVC, les rails \u00e0 rideaux, les roulements, les charni\u00e8res, les loquets, les \u00e9quipements de sport et de gymnastique et bien plus encore.\"}},{\"@type\":\"Question\",\"name\":\"Where can I use Silicone?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"3-IN-ONE Silicone Lubricant can be used for on Sliding Rails, uPVC Windows &amp; Doors, Curtain Rails, Bearings, Hinges, Catches, Sports and Gym Equipment and much more.\"}},{\"@type\":\"Question\",\"name\":\"Quand dois-je utiliser le p\u00e9n\u00e9trant ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Utilisez le p\u00e9n\u00e9trant haute performance 3-IN-ONE lorsque vous souhaitez desserrer facilement des \u00e9crous, des boulons, des serrures, des pi\u00e8ces ou des fixations rouill\u00e9s, coinc\u00e9s ou gripp\u00e9s.\"}},{\"@type\":\"Question\",\"name\":\"When should I use Penetrant?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Use 3-IN-ONE High Performance Penetrant when you want to loosen rusted, stuck or seized nuts, bolts, locks, parts or fixings with ease.\"}},{\"@type\":\"Question\",\"name\":\"O\u00f9 puis-je utiliser le p\u00e9n\u00e9trant ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Le p\u00e9n\u00e9trant haute performance 3-EN-UNE peut \u00eatre utilis\u00e9 pour les cha\u00eenes, les tuyaux, les \u00e9crous, les vis, les boulons, les serrures, les robinets, les raccords de porte et les portails. Il lib\u00e8re les pi\u00e8ces m\u00e9talliques gripp\u00e9es par la salet\u00e9, la rouille, la corrosion ou les d\u00e9p\u00f4ts graisseux s\u00e9ch\u00e9s.\"}},{\"@type\":\"Question\",\"name\":\"Where can I use Penetrant?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"3-IN-ONE High Performance Penetrant can be used for Chains, Pipes, Nuts, Screws, Bolts, Locks, Taps, Door Fittings and Gates. It frees metal parts seized by dirt, rust, corrosion, or dried-on greasy deposits.\"}},{\"@type\":\"Question\",\"name\":\"Le p\u00e9n\u00e9trant \u00e9limine-t-il la rouille ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Le p\u00e9n\u00e9trant haute performance 3-EN-UNE \u00e9limine la rouille et lib\u00e8re les pi\u00e8ces m\u00e9talliques bloqu\u00e9es par la salet\u00e9, la corrosion ou les d\u00e9p\u00f4ts graisseux s\u00e9ch\u00e9s.\"}},{\"@type\":\"Question\",\"name\":\"Will penetrant remove rust?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"3-IN-ONE High Performance Penetrant removes rust and frees metal parts seized by dirt, corrosion, or dried-on greasy deposits.\"}},{\"@type\":\"Question\",\"name\":\"Quand dois-je utiliser la graisse blanche au lithium ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Utilisez la graisse blanche au lithium 3-EN-UNE pour les projets impliquant des contacts m\u00e9tal-m\u00e9tal. Elle laisse une couche \u00e9paisse qui ne goutte pas et ne s'\u00e9coule pas, ce qui la rend parfaite pour les applications verticales et horizontales.\"}},{\"@type\":\"Question\",\"name\":\"When should I use White Lithium Grease?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Use 3-IN-ONE White Lithium Grease for projects involving metal-to-metal contacts. It leaves a thick coating that doesn\u2019t drip or run off, making it perfect for both vertical and horizontal applications.\"}},{\"@type\":\"Question\",\"name\":\"O\u00f9 puis-je utiliser la graisse White Lithium ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"La graisse blanche au lithium en spray 3-EN-UNE peut \u00eatre utilis\u00e9e sur les charni\u00e8res et les loquets, les portes, les roulements, les syst\u00e8mes de freinage, les portes coulissantes, les outils manuels et \u00e9lectriques et bien plus encore. La graisse blanche au lithium en spray 3-IN-ONE fonctionne \u00e0 des temp\u00e9ratures extr\u00eames (de -30 \u00b0C \u00e0 +140 \u00b0C), ce qui la rend id\u00e9ale pour une utilisation \u00e0 l'int\u00e9rieur et \u00e0 l'ext\u00e9rieur.\"}},{\"@type\":\"Question\",\"name\":\"Where can I use White Lithium Grease?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"3-IN-ONE White Lithium Grease Spray can be used on Hinges &amp; Latches, Gates, Bearings, Brake Systems, Sliding Doors, Hand &amp; Power Tools and much more. 3-IN-ONE White Lithium Grease Spray operates in extreme temperatures (-30 \u00b0C to +140 \u00b0C) making ideal for both indoor and outdoor use.\"}},{\"@type\":\"Question\",\"name\":\"L'huile 3-EN-UNE est-elle bonne pour les v\u00e9los ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"L'huile goutte \u00e0 goutte multi-usages 3-EN-UNE a \u00e9t\u00e9 con\u00e7ue \u00e0 l'origine pour fournir les trois \u00e9l\u00e9ments cl\u00e9s de l'entretien des bicyclettes : nettoyer, lubrifier et pr\u00e9venir la rouille. Elle peut encore \u00eatre utilis\u00e9e aujourd'hui dans le cadre de votre routine d'entretien des bicyclettes !\"}},{\"@type\":\"Question\",\"name\":\"Is 3-IN-ONE Oil good for bikes?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"3-IN-ONE Multi-Purpose Drip Oil was originally designed to deliver the 3 key elements of bicycle care and maintenance \u2013 Cleaning, Lubricating and Preventing rust. It can still be used as part of your bicycle maintenance routine today!\"}},{\"@type\":\"Question\",\"name\":\"Where can I use 3-IN-ONE Oil?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Use 3-IN-ONE Multi-Purpose Oil on nuts and bolts, hand and power tools, bearings, locks, fans, bicycles, rollers, wheels, drill bits, saw blades, ladders, seals, bearings, shafts, skateboards\u2014anything you want to move smoothly and quietly!\"}},{\"@type\":\"Question\",\"name\":\"O\u00f9 puis-je utiliser l'huile 3-EN-UNE ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Utilisez l'huile multi-usages 3-EN-UNE sur les \u00e9crous et les boulons, les outils manuels et \u00e9lectriques, les roulements, les serrures, les ventilateurs, les v\u00e9los, les rouleaux, les roues, les m\u00e8ches, les lames de scie, les \u00e9chelles, les joints, les roulements, les arbres, les planches \u00e0 roulettes - tout ce que vous voulez faire bouger en douceur et sans bruit !\"}}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/demande-de-droits-du-consommateur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demande de droits du consommateur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/\",\"name\":\"3-IN-ONE Canada\",\"description\":\"3-IN-ONE  Canada\",\"publisher\":{\"@id\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/#organization\"},\"alternateName\":\"3-IN-ONE CA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/#organization\",\"name\":\"3-IN-ONE Canada\",\"alternateName\":\"3-IN-ONE CA\",\"url\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.3inone.ca\\\/app\\\/uploads\\\/2022\\\/01\\\/01065730\\\/3in1-Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/media.3inone.ca\\\/app\\\/uploads\\\/2022\\\/01\\\/01065730\\\/3in1-Logo-1.png\",\"width\":1598,\"height\":1264,\"caption\":\"3-IN-ONE Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/3inone.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Original3INONEOil\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Demande de droits du consommateur - 3-IN-ONE Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/3inone.ca\/fr\/demande-de-droits-du-consommateur\/","og_locale":"fr_CA","og_type":"article","og_title":"Demande de droits du consommateur","og_url":"https:\/\/3inone.ca\/fr\/demande-de-droits-du-consommateur\/","og_site_name":"3-IN-ONE Canada","article_publisher":"https:\/\/www.facebook.com\/Original3INONEOil","og_image":[{"width":1598,"height":1264,"url":"https:\/\/media.3inone.ca\/app\/uploads\/2022\/01\/01065733\/3in1-Logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/3inone.ca\/fr\/demande-de-droits-du-consommateur\/","url":"https:\/\/3inone.ca\/fr\/demande-de-droits-du-consommateur\/","name":"Demande de droits du consommateur - 3-IN-ONE Canada","isPartOf":{"@id":"https:\/\/3inone.ca\/fr\/#website"},"datePublished":"2024-06-04T13:33:33+00:00","breadcrumb":{"@id":"https:\/\/3inone.ca\/fr\/demande-de-droits-du-consommateur\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/3inone.ca\/fr\/demande-de-droits-du-consommateur\/"]}],"mainEntity":[{"@type":"Question","name":"Comment vaporiser de la silicone sur un tapis de course ?","acceptedAnswer":{"@type":"Answer","text":"Il est important de lubrifier votre tapis de course pour qu'il fonctionne correctement. Avant de commencer, assurez-vous que votre appareil est d\u00e9branch\u00e9. Consultez le guide du fabricant pour savoir comment desserrer la courroie du tapis roulant afin de pouvoir la soulever et appliquer le lubrifiant. Utilisez le lubrifiant au silicone 3-IN-ONE ou le lubrifiant recommand\u00e9 par le fabricant et vaporisez sous la bande lorsque vous la soulevez. Laissez reposer quelques minutes pour permettre au solvant de s'\u00e9vaporer. R\u00e9p\u00e9tez l'op\u00e9ration des deux c\u00f4t\u00e9s de la machine, en veillant \u00e0 ne pas pulv\u00e9riser de lubrifiant sur le tapis. Si du lubrifiant est pulv\u00e9ris\u00e9 sur le tapis, utilisez de l'eau chaude savonneuse pour le nettoyer compl\u00e8tement. Rebranchez le tapis roulant et faites-le tourner \u00e0 faible vitesse pour permettre au produit de se r\u00e9pandre sur tout le dessous de l'appareil. Une fois le nettoyage termin\u00e9, essuyez les produits d'acc\u00e8s sur les c\u00f4t\u00e9s de l'appareil."}},{"@type":"Question","name":"How to silicone spray a treadmill?","acceptedAnswer":{"@type":"Answer","text":"It\u2019s important to lubricate your treadmill to keep it running smoothly. Before you start, make sure your device is unplugged. Check the manufacturer\u2019s guide for how to loosen the treadmill belt so that you can lift it and apply the lubricant. Use 3-IN-ONE Silicone Lubricant or the lubricant recommended by the manufacturer and spray underneath the belt as you lift it. Let this sit for a few minutes to allow the solvent to evaporate. Repeat the process on both sides of the machine, taking care not to spray any lubricant on top of the matting. If any lubricant is sprayed onto the matting, use hot, soapy water to clean thoroughly. Plug the treadmill back in and run it at a slow speed to allow the product to spread across the whole underside. Once complete, wipe away any access products from the sides of the machine."}},{"@type":"Question","name":"Spray au silicone - Quel est son r\u00f4le ?","acceptedAnswer":{"@type":"Answer","text":"Le lubrifiant au silicone 3-EN-UNE assure une lubrification et une protection anticorrosion de haute performance. Il forme un joint r\u00e9sistant \u00e0 l'eau pour prot\u00e9ger de l'humidit\u00e9 et fournit une couche protectrice au m\u00e9tal, au caoutchouc, au bois et au vinyle. Il r\u00e9duit la friction et l'usure des outils, des pi\u00e8ces et des \u00e9quipements et emp\u00eache la formation de rouille. Il s'agit d'une formulation \u00e0 s\u00e9chage rapide, qui ne tache pas et qui n'attire pas la poussi\u00e8re et la salet\u00e9."}},{"@type":"Question","name":"Silicone spray \u2013 what does it do?","acceptedAnswer":{"@type":"Answer","text":"3-IN-ONE Silicone Lubricant provides high-performance lubrication and corrosion protection. It provides a water-resistant seal to protect against moisture and provides a protective layer to metal, rubber, wood and vinyl. It reduces friction and wear on tools, parts and equipment and stops rust from forming. It is a quick drying, non-staining formulation that won\u2019t attract dust and dirt."}},{"@type":"Question","name":"Quand dois-je utiliser une silicone ?","acceptedAnswer":{"@type":"Answer","text":"Utilisez le lubrifiant au silicone 3-EN-UNE lorsque vous avez besoin d'un lubrifiant haute performance \u00e0 s\u00e9chage rapide qui peut \u00eatre utilis\u00e9 en toute s\u00e9curit\u00e9 sur le m\u00e9tal, le caoutchouc, le bois et le vinyle. Ce lubrifiant laisse un joint r\u00e9sistant \u00e0 l'eau, prot\u00e9geant ainsi de l'humidit\u00e9."}},{"@type":"Question","name":"When should I use a Silicone?","acceptedAnswer":{"@type":"Answer","text":"Use 3-IN-ONE Silicone Lubricant when you need a quick drying, high-performance lubricant that\u2019s safe for use on metal, rubber, wood and vinyl. This lubricant leaves a water-resistant seal, protecting against moisture."}},{"@type":"Question","name":"O\u00f9 puis-je utiliser le silicone ?","acceptedAnswer":{"@type":"Answer","text":"Le lubrifiant au silicone 3-EN-UNE peut \u00eatre utilis\u00e9 sur les rails coulissants, les portes et fen\u00eatres en PVC, les rails \u00e0 rideaux, les roulements, les charni\u00e8res, les loquets, les \u00e9quipements de sport et de gymnastique et bien plus encore."}},{"@type":"Question","name":"Where can I use Silicone?","acceptedAnswer":{"@type":"Answer","text":"3-IN-ONE Silicone Lubricant can be used for on Sliding Rails, uPVC Windows &amp; Doors, Curtain Rails, Bearings, Hinges, Catches, Sports and Gym Equipment and much more."}},{"@type":"Question","name":"Quand dois-je utiliser le p\u00e9n\u00e9trant ?","acceptedAnswer":{"@type":"Answer","text":"Utilisez le p\u00e9n\u00e9trant haute performance 3-IN-ONE lorsque vous souhaitez desserrer facilement des \u00e9crous, des boulons, des serrures, des pi\u00e8ces ou des fixations rouill\u00e9s, coinc\u00e9s ou gripp\u00e9s."}},{"@type":"Question","name":"When should I use Penetrant?","acceptedAnswer":{"@type":"Answer","text":"Use 3-IN-ONE High Performance Penetrant when you want to loosen rusted, stuck or seized nuts, bolts, locks, parts or fixings with ease."}},{"@type":"Question","name":"O\u00f9 puis-je utiliser le p\u00e9n\u00e9trant ?","acceptedAnswer":{"@type":"Answer","text":"Le p\u00e9n\u00e9trant haute performance 3-EN-UNE peut \u00eatre utilis\u00e9 pour les cha\u00eenes, les tuyaux, les \u00e9crous, les vis, les boulons, les serrures, les robinets, les raccords de porte et les portails. Il lib\u00e8re les pi\u00e8ces m\u00e9talliques gripp\u00e9es par la salet\u00e9, la rouille, la corrosion ou les d\u00e9p\u00f4ts graisseux s\u00e9ch\u00e9s."}},{"@type":"Question","name":"Where can I use Penetrant?","acceptedAnswer":{"@type":"Answer","text":"3-IN-ONE High Performance Penetrant can be used for Chains, Pipes, Nuts, Screws, Bolts, Locks, Taps, Door Fittings and Gates. It frees metal parts seized by dirt, rust, corrosion, or dried-on greasy deposits."}},{"@type":"Question","name":"Le p\u00e9n\u00e9trant \u00e9limine-t-il la rouille ?","acceptedAnswer":{"@type":"Answer","text":"Le p\u00e9n\u00e9trant haute performance 3-EN-UNE \u00e9limine la rouille et lib\u00e8re les pi\u00e8ces m\u00e9talliques bloqu\u00e9es par la salet\u00e9, la corrosion ou les d\u00e9p\u00f4ts graisseux s\u00e9ch\u00e9s."}},{"@type":"Question","name":"Will penetrant remove rust?","acceptedAnswer":{"@type":"Answer","text":"3-IN-ONE High Performance Penetrant removes rust and frees metal parts seized by dirt, corrosion, or dried-on greasy deposits."}},{"@type":"Question","name":"Quand dois-je utiliser la graisse blanche au lithium ?","acceptedAnswer":{"@type":"Answer","text":"Utilisez la graisse blanche au lithium 3-EN-UNE pour les projets impliquant des contacts m\u00e9tal-m\u00e9tal. Elle laisse une couche \u00e9paisse qui ne goutte pas et ne s'\u00e9coule pas, ce qui la rend parfaite pour les applications verticales et horizontales."}},{"@type":"Question","name":"When should I use White Lithium Grease?","acceptedAnswer":{"@type":"Answer","text":"Use 3-IN-ONE White Lithium Grease for projects involving metal-to-metal contacts. It leaves a thick coating that doesn\u2019t drip or run off, making it perfect for both vertical and horizontal applications."}},{"@type":"Question","name":"O\u00f9 puis-je utiliser la graisse White Lithium ?","acceptedAnswer":{"@type":"Answer","text":"La graisse blanche au lithium en spray 3-EN-UNE peut \u00eatre utilis\u00e9e sur les charni\u00e8res et les loquets, les portes, les roulements, les syst\u00e8mes de freinage, les portes coulissantes, les outils manuels et \u00e9lectriques et bien plus encore. La graisse blanche au lithium en spray 3-IN-ONE fonctionne \u00e0 des temp\u00e9ratures extr\u00eames (de -30 \u00b0C \u00e0 +140 \u00b0C), ce qui la rend id\u00e9ale pour une utilisation \u00e0 l'int\u00e9rieur et \u00e0 l'ext\u00e9rieur."}},{"@type":"Question","name":"Where can I use White Lithium Grease?","acceptedAnswer":{"@type":"Answer","text":"3-IN-ONE White Lithium Grease Spray can be used on Hinges &amp; Latches, Gates, Bearings, Brake Systems, Sliding Doors, Hand &amp; Power Tools and much more. 3-IN-ONE White Lithium Grease Spray operates in extreme temperatures (-30 \u00b0C to +140 \u00b0C) making ideal for both indoor and outdoor use."}},{"@type":"Question","name":"L'huile 3-EN-UNE est-elle bonne pour les v\u00e9los ?","acceptedAnswer":{"@type":"Answer","text":"L'huile goutte \u00e0 goutte multi-usages 3-EN-UNE a \u00e9t\u00e9 con\u00e7ue \u00e0 l'origine pour fournir les trois \u00e9l\u00e9ments cl\u00e9s de l'entretien des bicyclettes : nettoyer, lubrifier et pr\u00e9venir la rouille. Elle peut encore \u00eatre utilis\u00e9e aujourd'hui dans le cadre de votre routine d'entretien des bicyclettes !"}},{"@type":"Question","name":"Is 3-IN-ONE Oil good for bikes?","acceptedAnswer":{"@type":"Answer","text":"3-IN-ONE Multi-Purpose Drip Oil was originally designed to deliver the 3 key elements of bicycle care and maintenance \u2013 Cleaning, Lubricating and Preventing rust. It can still be used as part of your bicycle maintenance routine today!"}},{"@type":"Question","name":"Where can I use 3-IN-ONE Oil?","acceptedAnswer":{"@type":"Answer","text":"Use 3-IN-ONE Multi-Purpose Oil on nuts and bolts, hand and power tools, bearings, locks, fans, bicycles, rollers, wheels, drill bits, saw blades, ladders, seals, bearings, shafts, skateboards\u2014anything you want to move smoothly and quietly!"}},{"@type":"Question","name":"O\u00f9 puis-je utiliser l'huile 3-EN-UNE ?","acceptedAnswer":{"@type":"Answer","text":"Utilisez l'huile multi-usages 3-EN-UNE sur les \u00e9crous et les boulons, les outils manuels et \u00e9lectriques, les roulements, les serrures, les ventilateurs, les v\u00e9los, les rouleaux, les roues, les m\u00e8ches, les lames de scie, les \u00e9chelles, les joints, les roulements, les arbres, les planches \u00e0 roulettes - tout ce que vous voulez faire bouger en douceur et sans bruit !"}}]},{"@type":"BreadcrumbList","@id":"https:\/\/3inone.ca\/fr\/demande-de-droits-du-consommateur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/3inone.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Demande de droits du consommateur"}]},{"@type":"WebSite","@id":"https:\/\/3inone.ca\/fr\/#website","url":"https:\/\/3inone.ca\/fr\/","name":"3-IN-ONE Canada","description":"3-IN-ONE  Canada","publisher":{"@id":"https:\/\/3inone.ca\/fr\/#organization"},"alternateName":"3-IN-ONE CA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3inone.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/3inone.ca\/fr\/#organization","name":"3-IN-ONE Canada","alternateName":"3-IN-ONE CA","url":"https:\/\/3inone.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/3inone.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/media.3inone.ca\/app\/uploads\/2022\/01\/01065730\/3in1-Logo-1.png","contentUrl":"https:\/\/media.3inone.ca\/app\/uploads\/2022\/01\/01065730\/3in1-Logo-1.png","width":1598,"height":1264,"caption":"3-IN-ONE Canada"},"image":{"@id":"https:\/\/3inone.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Original3INONEOil"]}]}},"yoast-key-phrase":"","yoast-key-phrase-score":"","yoast-readability":"90","_links":{"self":[{"href":"https:\/\/3inone.ca\/fr\/wp-json\/wp\/v2\/pages\/3860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/3inone.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/3inone.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/3inone.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/3inone.ca\/fr\/wp-json\/wp\/v2\/comments?post=3860"}],"version-history":[{"count":1,"href":"https:\/\/3inone.ca\/fr\/wp-json\/wp\/v2\/pages\/3860\/revisions"}],"predecessor-version":[{"id":3861,"href":"https:\/\/3inone.ca\/fr\/wp-json\/wp\/v2\/pages\/3860\/revisions\/3861"}],"wp:attachment":[{"href":"https:\/\/3inone.ca\/fr\/wp-json\/wp\/v2\/media?parent=3860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}